{"id":982,"date":"2019-04-11T13:35:23","date_gmt":"2019-04-11T16:35:23","guid":{"rendered":"http:\/\/renatodias.online\/gyn\/?p=982"},"modified":"2019-04-11T13:35:23","modified_gmt":"2019-04-11T16:35:23","slug":"em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/","title":{"rendered":"Em cartaz o espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019"},"content":{"rendered":"<p>\t\t\t\t<strong>Exclusivo<\/strong><\/p>\n<p><strong>Dramaturgia \u00e0 luz da Psican\u00e1lise<\/strong><\/p>\n<p><strong>Em cartaz o espet\u00e1culo <\/strong><strong>\u2018<\/strong><strong>Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito<\/strong><strong>\u2019<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<figure id=\"attachment_51\" aria-describedby=\"caption-attachment-51\" style=\"width: 150px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/renatodias.online\/gyn\/wp-content\/uploads\/2019\/04\/renatodias.jpg\" alt=\"Renato Dias- Jornalista, Sociologo, Advogado, Escritor\" width=\"150\" height=\"150\" class=\"wp-image-51 size-full\" \/><figcaption id=\"caption-attachment-51\" class=\"wp-caption-text\">Renato Dias<\/figcaption><\/figure>\n<p><strong>Da Editoria do DM Revista<\/strong><\/p>\n<p>O espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 ser\u00e1\u00a0 apresentado nes\u00adta sexta-feira, no s\u00e1bado e no domingo no Teatro Goi\u00e2nia Ouro. Com 70 minutos de du\u00adra\u00e7\u00e3o. Sempre 20h. A classifica\u00e7\u00e3o et\u00e1ria \u00e9 livre. Uma produ\u00e7\u00e3o dramat\u00fargica, teatral, do N\u00fa\u00adcleo Freudiano de Psican\u00e1lise. Grupo fundado em 1985. Com o selo da Casa de Cultura Att\u00edlio Zamperoni. Assim como a impress\u00e3o digital da Companhia Theatral Gradiva. \u00c9 a 3\u00aa Tem\u00adpo\u00adrada. A produ\u00e7\u00e3o cultural leva a assinatura de Iza Valentim, informa a organiza\u00e7\u00e3o ao <strong>DM Revista.<\/strong><\/p>\n<figure id=\"attachment_983\" aria-describedby=\"caption-attachment-983\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/renatodias.online\/gyn\/wp-content\/uploads\/2019\/04\/53154976_1918991248212900_5393297751935025152_n-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"wp-image-983 size-medium\" \/><figcaption id=\"caption-attachment-983\" class=\"wp-caption-text\">Imagem dos atores em cena<\/figcaption><\/figure>\n<p>A dire\u00e7\u00e3o, segura, \u00e9 de Ivan Lima. Ator e diretor celebrado no mundo das artes. \u00a0Com carreira de sucesso. No Brasil e no Exterior. Atua\u00e7\u00f5es no teatro, no cinema e na televis\u00e3o. \u00c9 portador do Pr\u00eamio Personalidade cultural na It\u00e1lia. Do ano de 2015. Os atores s\u00e3o Renato Lucas e Celso Rabelo. Renato Lucas interpreta o personagem padre Ant\u00f4nio Vieira. \u00c9 psicanalista. Na segunda metade dos anos 70, ele atuou sob a dire\u00e7\u00e3o de Reinaldo de Montalv\u00e3o de Morais e Cunha. 1998: dirigiu e atuou na Leitura Dram\u00e1tica de \u2018\u00c9dipo-Rei\u2019, texto de H. Haydt de S. Mello<\/p>\n<p><strong>Personagem<\/strong><\/p>\n<p>Celso Rabelo protagoniza o papel do personagem padre Girolamo Cattaneo. \u00c9 advogado. O artista participou da adapta\u00e7\u00e3o do texto de \u2018Antinomia\u2019.\u00a0 Com atua\u00e7\u00e3o na leitura dram\u00e1tica da pe\u00e7a \u2018Laio\u2019,\u00a0 H.\u00a0 Haydt de S. Mello [2016]. Sob a dire\u00e7\u00e3o de Renato Mendon\u00e7a Lucas. O ator far\u00e1 a sua estreia no teatro. A pe\u00e7a produz um debate atual. Em tempo: o Brasil e o mundo vivem um per\u00edodo de contradi\u00e7\u00f5es nunca t\u00e3o explicitas e que revelam um universo dram\u00e1tico, conflituoso e tr\u00e1gico, \u00a0repleto de ideologias distintas, relata Iza Valentim ao <strong>Di\u00e1rio da Manh\u00e3.<\/strong><\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p><strong>Espet\u00e1culo:<\/strong> Teatro<\/p>\n<p><strong>Pe\u00e7a:<\/strong> \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019<\/p>\n<p><strong>Data:<\/strong> 12,13 e 14 de Abril [sexta, s\u00e1bado e domingo]<\/p>\n<p><strong>Local:<\/strong> Teatro Goi\u00e2nia Ouro [Antigo Cine Ouro, Rua 3, Centro]<\/p>\n<p><strong>Classifica\u00e7\u00e3o et\u00e1ria: <\/strong>Livre<\/p>\n<p><strong>Ingressos: R$ <\/strong>40,00, inteira e R$ 20,00 reais, meia\u00a0 [Idosos, Professores, Estudantes e Classe art\u00edstica]<\/p>\n<p><strong>Hor\u00e1rio: <\/strong>20h<\/p>\n<p><strong>Dura\u00e7\u00e3o: <\/strong>70 minutos<\/p>\n<p><strong>Observa\u00e7\u00e3o: <\/strong>Ap\u00f3s o espet\u00e1culo haver\u00e1 debate<strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/p>\n<p><strong>Espet\u00e1culo com os atores: <\/strong>Celso Rabelo e Renato Lucas<\/p>\n<p><strong>Produ\u00e7\u00e3o art\u00edstica:\u00a0<\/strong>K\u00e1tia Jacarand\u00e1<\/p>\n<p><strong>Produ\u00e7\u00e3o cultural: <\/strong>Iza Valentim<strong>\u00a0\u00a0<\/strong><\/p>\n<p><strong>Dire\u00e7\u00e3o: <\/strong>Ivan Lima<strong>\u00a0<\/strong>\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\t\t\t\tO espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 ser\u00e1\u00a0 apresentado nes\u00adta sexta-feira, no s\u00e1bado e no domingo no Teatro Goi\u00e2nia Ouro. Com 70 minutos de du\u00adra\u00e7\u00e3o. Sempre 20h\t\t<\/p>\n","protected":false},"author":2,"featured_media":984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em cartaz o espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em cartaz o espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 -\" \/>\n<meta property=\"og:description\" content=\"O espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 ser\u00e1\u00a0 apresentado nes\u00adta sexta-feira, no s\u00e1bado e no domingo no Teatro Goi\u00e2nia Ouro. Com 70 minutos de du\u00adra\u00e7\u00e3o. Sempre 20h\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-11T16:35:23+00:00\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"Em cartaz o espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019\",\"datePublished\":\"2019-04-11T16:35:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/\"},\"wordCount\":478,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/\",\"name\":\"Em cartaz o espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-04-11T16:35:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2019\\\/04\\\/11\\\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em cartaz o espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em cartaz o espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/","og_locale":"pt_BR","og_type":"article","og_title":"Em cartaz o espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 -","og_description":"O espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 ser\u00e1\u00a0 apresentado nes\u00adta sexta-feira, no s\u00e1bado e no domingo no Teatro Goi\u00e2nia Ouro. Com 70 minutos de du\u00adra\u00e7\u00e3o. Sempre 20h","og_url":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2019-04-11T16:35:23+00:00","author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"Em cartaz o espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019","datePublished":"2019-04-11T16:35:23+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/"},"wordCount":478,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#primaryimage"},"thumbnailUrl":"","articleSection":["Arte"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/","url":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/","name":"Em cartaz o espet\u00e1culo \u2018Antinomia - As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019 -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-04-11T16:35:23+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2019\/04\/11\/em-cartaz-o-espetaculo-antinomia-as-lagrimas-de-heraclito-e-o-riso-de-democrito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"Em cartaz o espet\u00e1culo \u2018Antinomia &#8211; As L\u00e1grimas de Her\u00e1clito e o Riso de Dem\u00f3crito\u2019"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=982"}],"version-history":[{"count":0,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}