{"id":22505,"date":"2026-05-12T16:31:15","date_gmt":"2026-05-12T19:31:15","guid":{"rendered":"https:\/\/renatodias.online\/movimento\/?p=22505"},"modified":"2026-05-12T16:31:15","modified_gmt":"2026-05-12T19:31:15","slug":"traldi-ve-queda-e-cre-em-virada","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/","title":{"rendered":"Traldi v\u00ea queda e cr\u00ea em virada\u00a0"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"144\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2026\/05\/Eleicoes-2026-e1778614026436.png\" alt=\"\" class=\"wp-image-22509\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Perillo vencer\u00e1, ele aposta\u00a0<\/mark><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Renato Dias&nbsp;<\/mark><\/strong><\/p>\n\n\n\n<p><strong>Os esc\u00e2ndalos sucessivos que atingem o Governo de Goi\u00e1s podem atingir Daniel Vilela [MDB] e fragilizar ainda mais o seu projeto de reelei\u00e7\u00e3o, avalia Hermes Traldi, ex-presidente da Associa\u00e7\u00e3o Goiana dos Ex-prefeitos [Agexp] e produtor rural.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Marconi-Perillo-1-e1712449987856.jpg\" alt=\"\" class=\"wp-image-19953\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Marconi-Perillo-1-e1712449987856.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Marconi-Perillo-1-e1712449987856-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Marconi-Perillo-1-e1712449987856-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>O analista do Tempo Presente diz que Marconi Perillo [PSDB e Cidadania], com uma plataforma republicana e n\u00e3o patrimonialista possui amplo potencial de crescimento, apontam as pesquisas de opini\u00e3o p\u00fablica para outubro.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Palacio-das-Esmeraldas-e1713994367661.jpg\" alt=\"\" class=\"wp-image-20186\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Palacio-das-Esmeraldas-e1713994367661.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Palacio-das-Esmeraldas-e1713994367661-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Palacio-das-Esmeraldas-e1713994367661-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>Graduado em Agronomia na USP, ele observa que o eleitor possui uma mem\u00f3ria afetiva do passado recente e recorda-se do Renda Cidad\u00e3, Bolsa Universit\u00e1ria, Cheque Moradia, FICA, Tenpo, UEG, Restaurante Cidad\u00e3o a somente R$1<\/strong>,00.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"248\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/08\/Caricatura-de-FHC-e1704564376781.jpg\" alt=\"\" class=\"wp-image-8350\"\/><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">FHC<\/mark><\/strong><\/figcaption><\/figure>\n\n\n\n<p><strong>De cultura enciclop\u00e9dica, forma\u00e7\u00e3o humanista e ideias socialdemocratas, o ex-prefeito de Goiatuba conta que o PSDB implantou o Real, liquidou com a infla\u00e7\u00e3o, criou a LRF, controlou o d\u00f3lar e distribuiu renda e privatizou estatais deficit\u00e1rias.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"70\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Saiba-mais-e1710783943468.png\" alt=\"\" class=\"wp-image-19880\"\/><\/figure>\n\n\n\n<p><strong>Hermes Traldi informa que Ot\u00e1vio Lage de Siqueira, na lista da Forbes, \u00e9 o nome ideal para compor, ao lado de Marconi Perillo, a chapa majorit\u00e1ria da coliga\u00e7\u00e3o centro &#8211; liberal em Goi\u00e1s. As op\u00e7\u00f5es ao Senado est\u00e3o em negocia\u00e7\u00e3o, afirma.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Gustavo-Sebba-2-e1710529223395.jpg\" alt=\"\" class=\"wp-image-19739\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Gustavo-Sebba-2-e1710529223395.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Gustavo-Sebba-2-e1710529223395-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Gustavo-Sebba-2-e1710529223395-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>A chapa para a Assembleia Legislativa possui candidatos com alta densidade eleitoral, relata. Como os deputados estaduais Gustavo Sebba, Jos\u00e9 Machado, Cl\u00e9cio Alves, Gugu Nader e o presidente da C\u00e2mara de Goi\u00e2nia, Rom\u00e1rio Policarpo<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Romario-Policarpo-e1716083473186.jpg\" alt=\"\" class=\"wp-image-19753\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Romario-Policarpo-e1716083473186.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Romario-Policarpo-e1716083473186-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Romario-Policarpo-e1716083473186-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>Gestor p\u00fablico eficiente, o dirigente conta que a lista dos pr\u00e9 &#8211; candidatos \u00e0 C\u00e2mara dos Deputados, em Bras\u00edlia, capital da Rep\u00fablica, cont\u00e9m os deputados federais Alcides Ribeiro e Jefferson Rodrigues e a vi\u00fava de Maguito Vilela Fl\u00e1via Teles.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/04\/Camara-dos-Deputados-e1774555520400.jpg\" alt=\"\" class=\"wp-image-20179\"\/><\/figure>\n\n\n\n<p><strong>Marconi Perillo far\u00e1 compara\u00e7\u00f5es de gest\u00e3o, apresentar\u00e1 as suas realiza\u00e7\u00f5es e ter\u00e1 espa\u00e7o para revelar os seus projetos e programas para os pr\u00f3ximos quatro anos e denunciar\u00e1 os erros, falhas e insufici\u00eancia de Daniel Vilela, atira.<\/strong><\/p>\n\n\n\n<p><strong>Daniel Vilela<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Ronaldo-Caiado-e1720494907285.jpg\" alt=\"\" class=\"wp-image-19754\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Ronaldo-Caiado-e1720494907285.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Ronaldo-Caiado-e1720494907285-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Ronaldo-Caiado-e1720494907285-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/02\/AUD-20240202-WA0029-online-audio-converter.com_.mp3\"><\/audio><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Chico Buarque, Apesar de voc\u00ea<\/mark><\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Perillo vencer\u00e1, ele aposta\u00a0 Renato Dias&nbsp; Os esc\u00e2ndalos sucessivos que atingem o Governo de Goi\u00e1s podem atingir Daniel Vilela [MDB] e fragilizar ainda mais o seu projeto de reelei\u00e7\u00e3o, avalia Hermes Traldi, ex-presidente da Associa\u00e7\u00e3o Goiana dos Ex-prefeitos [Agexp] e produtor rural. O analista do Tempo Presente diz que Marconi Perillo [PSDB e Cidadania], com<\/p>\n","protected":false},"author":2,"featured_media":20854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-22505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traldi v\u00ea queda e cr\u00ea em virada\u00a0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traldi v\u00ea queda e cr\u00ea em virada\u00a0 -\" \/>\n<meta property=\"og:description\" content=\"Perillo vencer\u00e1, ele aposta\u00a0 Renato Dias&nbsp; Os esc\u00e2ndalos sucessivos que atingem o Governo de Goi\u00e1s podem atingir Daniel Vilela [MDB] e fragilizar ainda mais o seu projeto de reelei\u00e7\u00e3o, avalia Hermes Traldi, ex-presidente da Associa\u00e7\u00e3o Goiana dos Ex-prefeitos [Agexp] e produtor rural. O analista do Tempo Presente diz que Marconi Perillo [PSDB e Cidadania], com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T19:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2025\/05\/Hermes-Traldi-1-e1747880434726.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"Traldi v\u00ea queda e cr\u00ea em virada\u00a0\",\"datePublished\":\"2026-05-12T19:31:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hermes-Traldi-1-e1747880434726.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/\",\"name\":\"Traldi v\u00ea queda e cr\u00ea em virada\u00a0 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hermes-Traldi-1-e1747880434726.jpg\",\"datePublished\":\"2026-05-12T19:31:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hermes-Traldi-1-e1747880434726.jpg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hermes-Traldi-1-e1747880434726.jpg\",\"width\":700,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2026\\\/05\\\/12\\\/traldi-ve-queda-e-cre-em-virada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traldi v\u00ea queda e cr\u00ea em virada\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traldi v\u00ea queda e cr\u00ea em virada\u00a0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/","og_locale":"pt_BR","og_type":"article","og_title":"Traldi v\u00ea queda e cr\u00ea em virada\u00a0 -","og_description":"Perillo vencer\u00e1, ele aposta\u00a0 Renato Dias&nbsp; Os esc\u00e2ndalos sucessivos que atingem o Governo de Goi\u00e1s podem atingir Daniel Vilela [MDB] e fragilizar ainda mais o seu projeto de reelei\u00e7\u00e3o, avalia Hermes Traldi, ex-presidente da Associa\u00e7\u00e3o Goiana dos Ex-prefeitos [Agexp] e produtor rural. O analista do Tempo Presente diz que Marconi Perillo [PSDB e Cidadania], com","og_url":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2026-05-12T19:31:15+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2025\/05\/Hermes-Traldi-1-e1747880434726.jpg","type":"image\/jpeg"}],"author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"Traldi v\u00ea queda e cr\u00ea em virada\u00a0","datePublished":"2026-05-12T19:31:15+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2025\/05\/Hermes-Traldi-1-e1747880434726.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/","url":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/","name":"Traldi v\u00ea queda e cr\u00ea em virada\u00a0 -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2025\/05\/Hermes-Traldi-1-e1747880434726.jpg","datePublished":"2026-05-12T19:31:15+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#primaryimage","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2025\/05\/Hermes-Traldi-1-e1747880434726.jpg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2025\/05\/Hermes-Traldi-1-e1747880434726.jpg","width":700,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2026\/05\/12\/traldi-ve-queda-e-cre-em-virada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"Traldi v\u00ea queda e cr\u00ea em virada\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/22505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=22505"}],"version-history":[{"count":3,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/22505\/revisions"}],"predecessor-version":[{"id":22510,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/22505\/revisions\/22510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media\/20854"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=22505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=22505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=22505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}