{"id":20410,"date":"2024-06-06T01:01:47","date_gmt":"2024-06-06T04:01:47","guid":{"rendered":"https:\/\/renatodias.online\/movimento\/?p=20410"},"modified":"2025-08-07T10:31:07","modified_gmt":"2025-08-07T13:31:07","slug":"altman-denuncia-crimes-de-israel","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/","title":{"rendered":"Altman denuncia crimes de Israel\u00a0"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Jornalista v\u00ea identidade com Apartheid&nbsp;<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Urgente-e1712698523959.jpg\" alt=\"\" class=\"wp-image-10966\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Editor do Opera Mundi em Goi\u00e2nia<\/mark>&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"321\" height=\"157\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2020\/03\/Breno-Altman-1.jpg\" alt=\"\" class=\"wp-image-3224\"\/><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-cyan-bluish-gray-color\">Breno Altman<\/mark><\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Renato Dias<\/mark>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>A Quest\u00e3o Palestina \u00e9 a r\u00e9gua moral do Tempo Presente, dispara o jornalista e editor do site Opera Mundi, <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Breno Altman<\/mark>. Ele \u00e9 autor do livro Contra o Sionismo _ Retrato de uma doutrina colonial e racista, Alameda.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Benjamin-Netanyahu-e1710527782497.jpg\" alt=\"\" class=\"wp-image-19791\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Benjamin-Netanyahu-e1710527782497.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Benjamin-Netanyahu-e1710527782497-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Benjamin-Netanyahu-e1710527782497-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>O pesquisador aponta, hoje, que o Sionismo teria sido fundado no s\u00e9culo 19. Com a publica\u00e7\u00e3o de O Estado Judeu, de <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Theodor Hertzel<\/mark>, ele explica. Uma etnocracia, afirma. Veja: de supremacia \u00e9tnica, racial, observa, cr\u00edtico.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"70\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Saiba-mais-e1710783943468.png\" alt=\"\" class=\"wp-image-19880\"\/><\/figure>\n\n\n\n<p><strong>As reais raz\u00f5es do movimento sionista na Palestina seria a ado\u00e7\u00e3o de uma <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">conex\u00e3o com a religi\u00e3o judaica fundamentalista<\/mark>. O Estado Judeu ter\u00e1 uma doutrina oficial, o Juda\u00edsmo, informa o escritor marxista.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"74\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Poder-e1710783884411.png\" alt=\"\" class=\"wp-image-19883\"\/><\/figure>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\">Discurso m\u00edtico e sedutor que anunciava a chegada de um suposto messias<\/mark>, na Palestina, pontua.&nbsp; Fundamental para a constru\u00e7\u00e3o do Estado Judeu, no s\u00e9culo 20. \u00c9 o que relata Breno Altman a www.renatodias.online<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"363\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Caricatura-de-Karl-Marx.png\" alt=\"\" class=\"wp-image-5301\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Caricatura-de-Karl-Marx.png 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Caricatura-de-Karl-Marx-248x300.png 248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\"><strong>Karl Marx<\/strong><\/figcaption><\/figure>\n\n\n\n<p><strong>Judeu, <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Karl Marx <\/mark>atribu\u00eda o \u00f3dio antissemita visceral \u00e0 explora\u00e7\u00e3o do capital credit\u00edcio e a \u00fanica sa\u00edda era a revolu\u00e7\u00e3o socialista e a constru\u00e7\u00e3o de uma sociedade sem classes, nem Estado, o comunismo, ele sublinha.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"174\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Revolucao-e1686252969943.png\" alt=\"\" class=\"wp-image-11529\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Revolucao-e1686252969943.png 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Revolucao-e1686252969943-150x87.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p><strong>Um ant\u00eddoto contra a influ\u00eancia das ideias de Karl Marx [1818-1883]. \u00c9 o que prometia entregar o Sionismo, registra o periodista. O projeto pol\u00edtico e expansionista imperialista tinha \u00e2ncora no <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-pink-color\">Oriente M\u00e9dio<\/mark>, metralha.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/04\/Bomba-A-morte-da-Politica-e1683416532524.jpg\" alt=\"explosivo\" class=\"wp-image-5888\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/04\/Bomba-A-morte-da-Politica-e1683416532524.jpg 150w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/04\/Bomba-A-morte-da-Politica-e1683416532524-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><figcaption class=\"wp-element-caption\"><strong>explosivo<\/strong><\/figcaption><\/figure>\n\n\n\n<p><strong>O Reino Unido comandava a expans\u00e3o imperial, destaca. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-light-green-cyan-color\">A Inglaterra queria enfraquecer o Imp\u00e9rio Turco-Otomano<\/mark>, frisa. O acordo que favoreceria o mundo \u00e1rabe \u00e9 tra\u00eddo, confidencia. Com os sionistas, n\u00e3o, atira.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-3-e1710530142560.jpg\" alt=\"\" class=\"wp-image-19816\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-3-e1710530142560.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-3-e1710530142560-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-3-e1710530142560-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>O Sionismo promove o desenvolvimento da coloniza\u00e7\u00e3o da Palestina por etapas, revela. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\">Os judeus enriquecem. Os palestinos empobrecem<\/mark>. Eles reagem e se revoltam. Sionistas reprimem. Com apoio brit\u00e2nico, reclama.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-2-e1710530179403.jpg\" alt=\"\" class=\"wp-image-19815\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-2-e1710530179403.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-2-e1710530179403-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-2-e1710530179403-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>A Assembleia Geral da ONU, em 1947, com o aval da Uni\u00e3o Sovi\u00e9tica, aprova a partilha, a divis\u00e3o, da Palestina, diz. Mais: os judeus expulsam 750 mil palestinos e passam a controlar 79% da regi\u00e3o, fuzila o rep\u00f3rter.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-1-e1710530103419.jpg\" alt=\"\" class=\"wp-image-19814\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-1-e1710530103419.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-1-e1710530103419-300x150.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Palestina-1-e1710530103419-150x75.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>Depois da Guerra dos Seis Dias, no ano de 1967, Israel obt\u00e9m 100% de hegemonia, estabelece um regime colonial e racista, como o do Apartheid que existiu na \u00c1frica do Sul, acusa, indignado, Breno Altman.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"503\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Card-Crimes-de-Israel-em-Infografico-e1709402457933.jpg\" alt=\"\" class=\"wp-image-19599\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Card-Crimes-de-Israel-em-Infografico-e1709402457933.jpg 400w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Card-Crimes-de-Israel-em-Infografico-e1709402457933-239x300.jpg 239w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2024\/03\/Card-Crimes-de-Israel-em-Infografico-e1709402457933-150x189.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p><strong>Os acordos de Oslo s\u00e3o assinados em 1993. Intifadas ocorrem. O Hamas ganha as elei\u00e7\u00f5es ao Parlamento. Israel, CEE e EUA n\u00e3o aceitam o resultado das urnas. Fatah e Hamas racham. Israel asfixia a Faixa de Gaza. Desde 2007.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"149\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/02\/A-crise-no-Peru-Mira-e1704731651532.png\" alt=\"\" class=\"wp-image-15687\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/02\/A-crise-no-Peru-Mira-e1704731651532.png 150w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/02\/A-crise-no-Peru-Mira-e1704731651532-96x96.png 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\n\n\n\n<p><strong>O dia 7 de outubro de 2023 \u00e9, sim, uma resposta, um contra-ataque, aos crimes de lesa-humanidade e de guerra de Israel, ataca. A Faixa de Gaza, em 2024, \u00e9 um gueto de Vars\u00f3via, desabafa, emocionado.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/07\/Tiros-e1710526721838.jpg\" alt=\"\" class=\"wp-image-17716\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/07\/Tiros-e1710526721838.jpg 100w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/07\/Tiros-e1710526721838-96x96.jpg 96w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/figure>\n\n\n\n<p><strong>Os palestinos e povos que lutam devem ser cultuados, n\u00e3o criticados, e possuem amparo do Direito Internacional, reitera. \u00c9 a autodefesa dos oprimidos, insiste. Solidariedade, reage. \u00c9 o lado certo da Hist\u00f3ria, ele acredita.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"71\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/08\/Sangue-1-e1710526772650.jpg\" alt=\"\" class=\"wp-image-17742\"\/><\/figure>\n\n\n\n<p><strong>Nunca o regime sionista esteve t\u00e3o isolado, cr\u00ea. O dia 7 de outubro de 2023 virou o jogo e a correla\u00e7\u00e3o de for\u00e7as no cen\u00e1rio pol\u00edtico internacional, conta. N\u00e3o custa lembrar tamb\u00e9m: Breno Altman \u00e9 um judeu antissionista.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/10\/AUD-20231001-WA0032.mp3\"><\/audio><figcaption class=\"wp-element-caption\"><strong>A Internacional<\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Jornalista v\u00ea identidade com Apartheid&nbsp; Editor do Opera Mundi em Goi\u00e2nia&nbsp; Renato Dias&nbsp; A Quest\u00e3o Palestina \u00e9 a r\u00e9gua moral do Tempo Presente, dispara o jornalista e editor do site Opera Mundi, Breno Altman. Ele \u00e9 autor do livro Contra o Sionismo _ Retrato de uma doutrina colonial e racista, Alameda. O pesquisador aponta, hoje,<\/p>\n","protected":false},"author":2,"featured_media":16690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[57,160,36,4],"tags":[],"class_list":["post-20410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista","category-historia","category-internacional","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Altman denuncia crimes de Israel\u00a0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altman denuncia crimes de Israel\u00a0 -\" \/>\n<meta property=\"og:description\" content=\"Jornalista v\u00ea identidade com Apartheid&nbsp; Editor do Opera Mundi em Goi\u00e2nia&nbsp; Renato Dias&nbsp; A Quest\u00e3o Palestina \u00e9 a r\u00e9gua moral do Tempo Presente, dispara o jornalista e editor do site Opera Mundi, Breno Altman. Ele \u00e9 autor do livro Contra o Sionismo _ Retrato de uma doutrina colonial e racista, Alameda. O pesquisador aponta, hoje,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T04:01:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T13:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/05\/Breno-Altman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"Altman denuncia crimes de Israel\u00a0\",\"datePublished\":\"2024-06-06T04:01:47+00:00\",\"dateModified\":\"2025-08-07T13:31:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Breno-Altman.jpg\",\"articleSection\":[\"Entrevista\",\"Hist\u00f3ria\",\"Internacional\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/\",\"name\":\"Altman denuncia crimes de Israel\u00a0 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Breno-Altman.jpg\",\"datePublished\":\"2024-06-06T04:01:47+00:00\",\"dateModified\":\"2025-08-07T13:31:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Breno-Altman.jpg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Breno-Altman.jpg\",\"width\":800,\"height\":531,\"caption\":\"Breno Altman\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2024\\\/06\\\/06\\\/altman-denuncia-crimes-de-israel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altman denuncia crimes de Israel\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altman denuncia crimes de Israel\u00a0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/","og_locale":"pt_BR","og_type":"article","og_title":"Altman denuncia crimes de Israel\u00a0 -","og_description":"Jornalista v\u00ea identidade com Apartheid&nbsp; Editor do Opera Mundi em Goi\u00e2nia&nbsp; Renato Dias&nbsp; A Quest\u00e3o Palestina \u00e9 a r\u00e9gua moral do Tempo Presente, dispara o jornalista e editor do site Opera Mundi, Breno Altman. Ele \u00e9 autor do livro Contra o Sionismo _ Retrato de uma doutrina colonial e racista, Alameda. O pesquisador aponta, hoje,","og_url":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2024-06-06T04:01:47+00:00","article_modified_time":"2025-08-07T13:31:07+00:00","og_image":[{"width":800,"height":531,"url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/05\/Breno-Altman.jpg","type":"image\/jpeg"}],"author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"Altman denuncia crimes de Israel\u00a0","datePublished":"2024-06-06T04:01:47+00:00","dateModified":"2025-08-07T13:31:07+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/05\/Breno-Altman.jpg","articleSection":["Entrevista","Hist\u00f3ria","Internacional","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/","url":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/","name":"Altman denuncia crimes de Israel\u00a0 -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/05\/Breno-Altman.jpg","datePublished":"2024-06-06T04:01:47+00:00","dateModified":"2025-08-07T13:31:07+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#primaryimage","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/05\/Breno-Altman.jpg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/05\/Breno-Altman.jpg","width":800,"height":531,"caption":"Breno Altman"},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2024\/06\/06\/altman-denuncia-crimes-de-israel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"Altman denuncia crimes de Israel\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/20410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=20410"}],"version-history":[{"count":4,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/20410\/revisions"}],"predecessor-version":[{"id":21165,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/20410\/revisions\/21165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media\/16690"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=20410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=20410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=20410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}