{"id":18865,"date":"2023-11-30T19:05:05","date_gmt":"2023-11-30T22:05:05","guid":{"rendered":"https:\/\/renatodias.online\/movimento\/?p=18865"},"modified":"2023-11-30T19:05:06","modified_gmt":"2023-11-30T22:05:06","slug":"perillo-e-presidente-nacional-do-psdb","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/","title":{"rendered":"<strong>Perillo \u00e9 presidente nacional do PSDB<\/strong>"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>Foco nas elei\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/06\/Eleicoes-de-2024.png\" alt=\"\" class=\"wp-image-17086\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Projeto para Pal\u00e1cio do Planalto<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2019\/09\/Tucano-e1637493554237.gif\" alt=\"\" class=\"wp-image-2542\"\/><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Tucano, o s\u00edmbolo do PSDB<\/mark><\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Renato Dias<\/mark><\/strong><\/p>\n\n\n\n<p>Governador do Estado de Goi\u00e1s por quatro mandatos e ainda ex-senador da Rep\u00fablica, <strong>Marconi Perillo<\/strong> \u00e9 o novo presidente nacional do Partido da Socialdemocracia Brasileira.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/08\/Raio-X-especial-e1680139645191.png\" alt=\"\" class=\"wp-image-13781\"\/><\/figure>\n\n\n\n<p>O ex-deputado federal \u00e9 graduado em Direito, casado com <strong>Valeria Jayme<\/strong> e pai de duas filhas tem um ex\u00e9rcito com <strong>dois governadores<\/strong>, <strong>dois senadores<\/strong> e <strong>13 federais<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/04\/Veja-e1680475225663.jpg\" alt=\"\" class=\"wp-image-16291\"\/><\/figure>\n\n\n\n<p>O governador do Estado do Rio Grande do Sul, <strong>Eduardo Leite<\/strong>, ocupar\u00e1 uma das vice- presid\u00eancias da legenda que possui o tucano como s\u00edmbolo, al\u00e9m do n\u00famero 45.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"103\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/08\/Saiba-mais-e1680139445250.png\" alt=\"\" class=\"wp-image-13698\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/08\/Saiba-mais-e1680139445250.png 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/08\/Saiba-mais-e1680139445250-150x52.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>Veja: o projeto pol\u00edtico do cardeal tucano \u00e9 organizar a Federa\u00e7\u00e3o PSDB e Cidadania para as urnas de 2024, a corrida <strong>ao Pal\u00e1cio do Planalto em 2026<\/strong>. Com nome pr\u00f3prio.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/05\/Palacio-do-Planalto-e1701381686309.jpg\" alt=\"\" class=\"wp-image-6850\"\/><figcaption class=\"wp-element-caption\"><strong>Pal\u00e1cio do Planalto<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Eduardo Leite e Marconi Perillo s\u00e3o cotados para as elei\u00e7\u00f5es \u00e0 <strong>Presid\u00eancia da Rep\u00fablica<\/strong>. O l\u00edder do PSDB em Goi\u00e1s \u00e9 tamb\u00e9m op\u00e7\u00e3o \u00e0 <strong>Casa Verde<\/strong> e ao <strong>Senado<\/strong>, em 2026.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/02\/Eduardo-Leite-Caricatura.jpg\" alt=\"\" class=\"wp-image-15452\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Foco nas elei\u00e7\u00f5es Projeto para Pal\u00e1cio do Planalto Renato Dias Governador do Estado de Goi\u00e1s por quatro mandatos e ainda ex-senador da Rep\u00fablica, Marconi Perillo \u00e9 o novo presidente nacional do Partido da Socialdemocracia Brasileira. O ex-deputado federal \u00e9 graduado em Direito, casado com Valeria Jayme e pai de duas filhas tem um ex\u00e9rcito com<\/p>\n","protected":false},"author":2,"featured_media":13417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[159,35,4],"tags":[],"class_list":["post-18865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eleicoes","category-nacional","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perillo \u00e9 presidente nacional do PSDB -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perillo \u00e9 presidente nacional do PSDB -\" \/>\n<meta property=\"og:description\" content=\"Foco nas elei\u00e7\u00f5es Projeto para Pal\u00e1cio do Planalto Renato Dias Governador do Estado de Goi\u00e1s por quatro mandatos e ainda ex-senador da Rep\u00fablica, Marconi Perillo \u00e9 o novo presidente nacional do Partido da Socialdemocracia Brasileira. O ex-deputado federal \u00e9 graduado em Direito, casado com Valeria Jayme e pai de duas filhas tem um ex\u00e9rcito com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T22:05:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-30T22:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/07\/Marconi-Perillo-especial-e1701381877684.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"Perillo \u00e9 presidente nacional do PSDB\",\"datePublished\":\"2023-11-30T22:05:05+00:00\",\"dateModified\":\"2023-11-30T22:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Marconi-Perillo-especial-e1704408302721.jpg\",\"articleSection\":[\"Elei\u00e7\u00f5es\",\"Nacional\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/\",\"name\":\"Perillo \u00e9 presidente nacional do PSDB -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Marconi-Perillo-especial-e1704408302721.jpg\",\"datePublished\":\"2023-11-30T22:05:05+00:00\",\"dateModified\":\"2023-11-30T22:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Marconi-Perillo-especial-e1704408302721.jpg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Marconi-Perillo-especial-e1704408302721.jpg\",\"width\":300,\"height\":218,\"caption\":\"Marconi Perillo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2023\\\/11\\\/30\\\/perillo-e-presidente-nacional-do-psdb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perillo \u00e9 presidente nacional do PSDB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perillo \u00e9 presidente nacional do PSDB -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/","og_locale":"pt_BR","og_type":"article","og_title":"Perillo \u00e9 presidente nacional do PSDB -","og_description":"Foco nas elei\u00e7\u00f5es Projeto para Pal\u00e1cio do Planalto Renato Dias Governador do Estado de Goi\u00e1s por quatro mandatos e ainda ex-senador da Rep\u00fablica, Marconi Perillo \u00e9 o novo presidente nacional do Partido da Socialdemocracia Brasileira. O ex-deputado federal \u00e9 graduado em Direito, casado com Valeria Jayme e pai de duas filhas tem um ex\u00e9rcito com","og_url":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2023-11-30T22:05:05+00:00","article_modified_time":"2023-11-30T22:05:06+00:00","og_image":[{"width":700,"height":508,"url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/07\/Marconi-Perillo-especial-e1701381877684.jpg","type":"image\/jpeg"}],"author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"Perillo \u00e9 presidente nacional do PSDB","datePublished":"2023-11-30T22:05:05+00:00","dateModified":"2023-11-30T22:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/07\/Marconi-Perillo-especial-e1704408302721.jpg","articleSection":["Elei\u00e7\u00f5es","Nacional","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/","url":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/","name":"Perillo \u00e9 presidente nacional do PSDB -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/07\/Marconi-Perillo-especial-e1704408302721.jpg","datePublished":"2023-11-30T22:05:05+00:00","dateModified":"2023-11-30T22:05:06+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#primaryimage","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/07\/Marconi-Perillo-especial-e1704408302721.jpg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/07\/Marconi-Perillo-especial-e1704408302721.jpg","width":300,"height":218,"caption":"Marconi Perillo"},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2023\/11\/30\/perillo-e-presidente-nacional-do-psdb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"Perillo \u00e9 presidente nacional do PSDB"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/18865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=18865"}],"version-history":[{"count":1,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/18865\/revisions"}],"predecessor-version":[{"id":18866,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/18865\/revisions\/18866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media\/13417"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=18865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=18865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=18865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}