{"id":13004,"date":"2022-06-29T16:49:56","date_gmt":"2022-06-29T19:49:56","guid":{"rendered":"https:\/\/renatodias.online\/movimento\/?p=13004"},"modified":"2022-06-29T16:49:56","modified_gmt":"2022-06-29T19:49:56","slug":"isaura-lemos-disputa-eleicao","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/","title":{"rendered":"Isaura Lemos disputa elei\u00e7\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11445 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Eleicoes-de-2022.jpeg\" alt=\"\" width=\"639\" height=\"361\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Eleicoes-de-2022.jpeg 639w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Eleicoes-de-2022-300x169.jpeg 300w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\" \/><\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>Isaura Lemos disputa elei\u00e7\u00e3o<\/strong><\/span><\/h1>\n<h1 style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11468 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Centenario-do-PC-do-B.jpg\" alt=\"\" width=\"600\" height=\"282\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Centenario-do-PC-do-B.jpg 600w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Centenario-do-PC-do-B-300x141.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>\u00c0 Assembleia Legislativa<\/strong><\/span><\/h1>\n<p><strong>Renato Dias<\/strong><\/p>\n<p>A ex-presidente do PC do B em Goi\u00e1s <strong>Isaura Lemos \u00e9 pr\u00e9-candidata a deputada estadual<\/strong>. Pela <strong>Federa\u00e7\u00e3o Brasil Esperan\u00e7a<\/strong>. <strong>Com PT e PV.<\/strong> As elei\u00e7\u00f5es ser\u00e3o realizadas no pr\u00f3ximo dia 2 de outubro. Com urnas eletr\u00f4nicas.<\/p>\n<figure id=\"attachment_11710\" aria-describedby=\"caption-attachment-11710\" style=\"width: 933px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11710 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/04\/Sessao-especial-Isaura-Lemos.jpg\" alt=\"\" width=\"933\" height=\"623\" \/><figcaption id=\"caption-attachment-11710\" class=\"wp-caption-text\"><strong>Isaura Lemos<\/strong><\/figcaption><\/figure>\n<blockquote>\n<h1><span style=\"color: #ff0000;\"><strong>Republicana, n\u00e3o patrimonialista e socialista\u00a0<\/strong><\/span><\/h1>\n<\/blockquote>\n<p>Com uma plataforma republicana. Mais: n\u00e3o patrimonialista, em defesa do socialismo, o PC do B quer a derrubada do presidente da Rep\u00fablica, Jair Messias Bolsonaro [PL]. Com 700 mil mortes sob a Pandemia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7291 aligncenter\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/06\/Bandeira-do-PC-do-B.jpg\" alt=\"\" width=\"500\" height=\"459\" \/><\/p>\n<blockquote>\n<h1><strong><span style=\"color: #ff0000;\">Cinco mandatos consecutivos de deputada estadual<\/span>\u00a0<\/strong><\/h1>\n<\/blockquote>\n<p>Ex-deputada estadual por cinco mandatos consecutivos, Isaura Lemos trabalha Full Time pela elei\u00e7\u00e3o, j\u00e1 no primeiro turno, do ex-presidente da Rep\u00fablica Luiz In\u00e1cio Lula da Silva e Geraldo Alckmin em sua vice.<\/p>\n<figure id=\"attachment_5361\" aria-describedby=\"caption-attachment-5361\" style=\"width: 112px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5361\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Luiz-Inacio-Lula-da-Silva-1-112x300.jpg\" alt=\"Luiz In\u00e1cio Lula da Silva \u2013 caricatura\" width=\"112\" height=\"300\" \/><figcaption id=\"caption-attachment-5361\" class=\"wp-caption-text\"><strong>Luiz In\u00e1cio Lula da Silva <br \/><\/strong><\/figcaption><\/figure>\n<blockquote>\n<h1><strong><span style=\"color: #ff0000;\">Projetos de oposi\u00e7\u00e3o a Jair Bolsonaro e Ronaldo Caiado<\/span>\u00a0<\/strong><\/h1>\n<\/blockquote>\n<p>A l\u00edder dos sem teto, dos sem terras, dos trabalhadores da cidade e do campo e da legi\u00e3o de desempregados \u00e9 oposi\u00e7\u00e3o tanto a Jair Messias Bolsonaro quanto ao governador de Goi\u00e1s, Ronaldo Caiado [UB].<\/p>\n<figure id=\"attachment_12876\" aria-describedby=\"caption-attachment-12876\" style=\"width: 196px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12876\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/06\/Jair-Bolsonaro-Autogolpe-196x300.jpg\" alt=\"\" width=\"196\" height=\"300\" \/><figcaption id=\"caption-attachment-12876\" class=\"wp-caption-text\"><strong>Jair Bolsonaro &#8211; Cr\u00e9dito: Isto \u00e9<\/strong><\/figcaption><\/figure>\n<blockquote>\n<h1><span style=\"color: #ff0000;\"><strong>Mem\u00f3rias da luta clandestina contra a ditadura<\/strong><\/span><\/h1>\n<\/blockquote>\n<p>Adepta das ideias de Karl Marx, Friedrich Engels, Vladimir Ilich Ulianov [L\u00eanin] e leitora de Antonio Gramsci, a dirigente participou da luta clandestina contra a ditadura civil e militar no Brasil. Na AP e depois PC do B.<\/p>\n<figure id=\"attachment_5301\" aria-describedby=\"caption-attachment-5301\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5301 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Caricatura-de-Karl-Marx.png\" alt=\"\" width=\"300\" height=\"363\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Caricatura-de-Karl-Marx.png 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/03\/Caricatura-de-Karl-Marx-248x300.png 248w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-5301\" class=\"wp-caption-text\"><strong>Karl Marx<\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Isaura Lemos disputa elei\u00e7\u00e3o \u00c0 Assembleia Legislativa Renato Dias A ex-presidente do PC do B em Goi\u00e1s Isaura Lemos \u00e9 pr\u00e9-candidata a deputada estadual. Pela Federa\u00e7\u00e3o Brasil Esperan\u00e7a. Com PT e PV. As elei\u00e7\u00f5es ser\u00e3o realizadas no pr\u00f3ximo dia 2 de outubro. Com urnas eletr\u00f4nicas. Republicana, n\u00e3o patrimonialista e socialista\u00a0 Com uma plataforma republicana. Mais:<\/p>\n","protected":false},"author":2,"featured_media":9687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-13004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isaura Lemos disputa elei\u00e7\u00e3o -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isaura Lemos disputa elei\u00e7\u00e3o -\" \/>\n<meta property=\"og:description\" content=\"Isaura Lemos disputa elei\u00e7\u00e3o \u00c0 Assembleia Legislativa Renato Dias A ex-presidente do PC do B em Goi\u00e1s Isaura Lemos \u00e9 pr\u00e9-candidata a deputada estadual. Pela Federa\u00e7\u00e3o Brasil Esperan\u00e7a. Com PT e PV. As elei\u00e7\u00f5es ser\u00e3o realizadas no pr\u00f3ximo dia 2 de outubro. Com urnas eletr\u00f4nicas. Republicana, n\u00e3o patrimonialista e socialista\u00a0 Com uma plataforma republicana. Mais:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T19:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/11\/Isaura-lemos-2-e1648175777995.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"Isaura Lemos disputa elei\u00e7\u00e3o\",\"datePublished\":\"2022-06-29T19:49:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/\"},\"wordCount\":276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Isaura-lemos-2-e1648175777995.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/\",\"name\":\"Isaura Lemos disputa elei\u00e7\u00e3o -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Isaura-lemos-2-e1648175777995.jpg\",\"datePublished\":\"2022-06-29T19:49:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Isaura-lemos-2-e1648175777995.jpg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Isaura-lemos-2-e1648175777995.jpg\",\"width\":370,\"height\":247,\"caption\":\"Isaura Lemos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/06\\\/29\\\/isaura-lemos-disputa-eleicao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isaura Lemos disputa elei\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isaura Lemos disputa elei\u00e7\u00e3o -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/","og_locale":"pt_BR","og_type":"article","og_title":"Isaura Lemos disputa elei\u00e7\u00e3o -","og_description":"Isaura Lemos disputa elei\u00e7\u00e3o \u00c0 Assembleia Legislativa Renato Dias A ex-presidente do PC do B em Goi\u00e1s Isaura Lemos \u00e9 pr\u00e9-candidata a deputada estadual. Pela Federa\u00e7\u00e3o Brasil Esperan\u00e7a. Com PT e PV. As elei\u00e7\u00f5es ser\u00e3o realizadas no pr\u00f3ximo dia 2 de outubro. Com urnas eletr\u00f4nicas. Republicana, n\u00e3o patrimonialista e socialista\u00a0 Com uma plataforma republicana. Mais:","og_url":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2022-06-29T19:49:56+00:00","og_image":[{"width":370,"height":247,"url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/11\/Isaura-lemos-2-e1648175777995.jpg","type":"image\/jpeg"}],"author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"Isaura Lemos disputa elei\u00e7\u00e3o","datePublished":"2022-06-29T19:49:56+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/"},"wordCount":276,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/11\/Isaura-lemos-2-e1648175777995.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/","url":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/","name":"Isaura Lemos disputa elei\u00e7\u00e3o -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/11\/Isaura-lemos-2-e1648175777995.jpg","datePublished":"2022-06-29T19:49:56+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#primaryimage","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/11\/Isaura-lemos-2-e1648175777995.jpg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/11\/Isaura-lemos-2-e1648175777995.jpg","width":370,"height":247,"caption":"Isaura Lemos"},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2022\/06\/29\/isaura-lemos-disputa-eleicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"Isaura Lemos disputa elei\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/13004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=13004"}],"version-history":[{"count":1,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/13004\/revisions"}],"predecessor-version":[{"id":13005,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/13004\/revisions\/13005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media\/9687"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=13004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=13004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=13004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}