{"id":12213,"date":"2022-05-05T19:46:16","date_gmt":"2022-05-05T22:46:16","guid":{"rendered":"https:\/\/renatodias.online\/movimento\/?p=12213"},"modified":"2022-05-05T19:46:16","modified_gmt":"2022-05-05T22:46:16","slug":"peixoto-na-corrida-a-camara-federal","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/","title":{"rendered":"Peixoto na corrida \u00e0 C\u00e2mara Federal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11445 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Eleicoes-de-2022.jpeg\" alt=\"\" width=\"639\" height=\"361\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Eleicoes-de-2022.jpeg 639w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Eleicoes-de-2022-300x169.jpeg 300w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\" \/><\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong>Peixoto na corrida \u00e0 C\u00e2mara Federal<\/strong><\/span><\/h1>\n<figure id=\"attachment_6053\" aria-describedby=\"caption-attachment-6053\" style=\"width: 685px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6053 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/04\/Congresso-Nacional.jpg\" alt=\"Congresso Nacional\" width=\"685\" height=\"268\" \/><figcaption id=\"caption-attachment-6053\" class=\"wp-caption-text\"><strong>Congresso Nacional<\/strong><\/figcaption><\/figure>\n<h1 style=\"text-align: center;\"><span style=\"color: #800080;\"><strong>Liberal quer fim do Fund\u00e3o Eleitoral<\/strong><\/span><\/h1>\n<figure id=\"attachment_8500\" aria-describedby=\"caption-attachment-8500\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8500\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/08\/Sebastiao-Peixoto-vereador-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" \/><figcaption id=\"caption-attachment-8500\" class=\"wp-caption-text\"><strong>Sebasti\u00e3o Peixoto, vereador em Goi\u00e2nia<\/strong><\/figcaption><\/figure>\n<figure id=\"attachment_5888\" aria-describedby=\"caption-attachment-5888\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5888\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/04\/Bomba-A-morte-da-Politica-300x300.jpg\" alt=\"explosivo\" width=\"300\" height=\"300\" \/><figcaption id=\"caption-attachment-5888\" class=\"wp-caption-text\"><strong><span style=\"color: #ff6600;\">explosivo<\/span><\/strong><\/figcaption><\/figure>\n<h2 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>Ele prop\u00f5e PEC para acabar com farra dos concurseiros<\/strong><\/span><\/h2>\n<p><strong>Renato Dias<\/strong><\/p>\n<p>O suplente de vereador Sebasti\u00e3o Peixoto anuncia, hoje, a sua pr\u00e9-candidatura \u00e0 C\u00e2mara dos Deputados. Legenda: Solidariedade. As elei\u00e7\u00f5es ocorrer\u00e3o dia 2; de outubro de 2022. Goi\u00e1s tem 17 cadeiras. Com 4 milh\u00f5es e 800 mil eleitores. Uma popula\u00e7\u00e3o de 7,2 mi. Dados do TSE.<\/p>\n<blockquote>\n<h1><span style=\"color: #0000ff;\"><strong>Legenda quer eleger dois deputados federais<\/strong><\/span><\/h1>\n<\/blockquote>\n<p style=\"text-align: right;\"><strong><span style=\"color: #993300;\">Sebasti\u00e3o Peixoto [Solidariedade]<\/span><\/strong><\/p>\n<p>O deputado federal Paulinho da For\u00e7a Sindical \u00e9 o presidente da sigla nacional. J\u00e1 o parlamentar Lucas Verg\u00edlio preside a agremia\u00e7\u00e3o no Estado. A proje\u00e7\u00e3o pol\u00edtica \u00e9 da conquista de duas vagas, em Bras\u00edlia [DF], na capital da Rep\u00fablica, informa ele ao Portal de Not\u00edcias www.renatodias.online<\/p>\n<blockquote>\n<h1><span style=\"color: #0000ff;\"><strong>Agenda republicana e n\u00e3o patrimonialista<\/strong><\/span><\/h1>\n<\/blockquote>\n<p style=\"text-align: right;\"><strong><span style=\"color: #993300;\">Sebasti\u00e3o Peixoto [Solidariedade]<\/span><\/strong><\/p>\n<p>Com uma plataforma republicana e n\u00e3o patrimonialista, Sebasti\u00e3o Peixoto, caso seja eleito, diz que apresentar\u00e1 Projeto de Emenda Constitucional [PEC] para acabar com o Fund\u00e3o Eleitoral, hoje de R$ 4,9 bi, reduzir os superpoderes do MP. O MP assassina reputa\u00e7\u00f5es, desabafa.<\/p>\n<blockquote>\n<h1><span style=\"color: #0000ff;\"><strong>Em defesa da desdolariza\u00e7\u00e3o dos combust\u00edveis<\/strong><\/span><\/h1>\n<\/blockquote>\n<p style=\"text-align: right;\"><span style=\"color: #993300;\"><strong>Sebasti\u00e3o Peixoto [Solidariedade]<\/strong><\/span><\/p>\n<p>Advogado graduado na PUC, homem do agroneg\u00f3cio, setor prim\u00e1rio da economia, empres\u00e1rio da \u00e1rea de combust\u00edveis, o l\u00edder do Solidariedade defende a aprova\u00e7\u00e3o de lei que restringe a inscri\u00e7\u00e3o em concurso p\u00fablico apenas aos moradores nascidos nos seus respectivos munic\u00edpios e Estados.<\/p>\n<figure id=\"attachment_11131\" aria-describedby=\"caption-attachment-11131\" style=\"width: 576px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11131\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/03\/Sebastiao-Peixoto-pre-candidato.jpg\" alt=\"\" width=\"576\" height=\"1024\" \/><figcaption id=\"caption-attachment-11131\" class=\"wp-caption-text\"><strong>Sebasti\u00e3o Peixoto \u00e9 pr\u00e9-candidato<\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Peixoto na corrida \u00e0 C\u00e2mara Federal Liberal quer fim do Fund\u00e3o Eleitoral Ele prop\u00f5e PEC para acabar com farra dos concurseiros Renato Dias O suplente de vereador Sebasti\u00e3o Peixoto anuncia, hoje, a sua pr\u00e9-candidatura \u00e0 C\u00e2mara dos Deputados. Legenda: Solidariedade. As elei\u00e7\u00f5es ocorrer\u00e3o dia 2; de outubro de 2022. Goi\u00e1s tem 17 cadeiras. Com 4<\/p>\n","protected":false},"author":2,"featured_media":9162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peixoto na corrida \u00e0 C\u00e2mara Federal -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peixoto na corrida \u00e0 C\u00e2mara Federal -\" \/>\n<meta property=\"og:description\" content=\"Peixoto na corrida \u00e0 C\u00e2mara Federal Liberal quer fim do Fund\u00e3o Eleitoral Ele prop\u00f5e PEC para acabar com farra dos concurseiros Renato Dias O suplente de vereador Sebasti\u00e3o Peixoto anuncia, hoje, a sua pr\u00e9-candidatura \u00e0 C\u00e2mara dos Deputados. Legenda: Solidariedade. As elei\u00e7\u00f5es ocorrer\u00e3o dia 2; de outubro de 2022. Goi\u00e1s tem 17 cadeiras. Com 4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T22:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/09\/Suplente-de-vereador-Sebastiao-Peixoto-e1646620052462.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"Peixoto na corrida \u00e0 C\u00e2mara Federal\",\"datePublished\":\"2022-05-05T22:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg\",\"articleSection\":[\"Cinema\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/\",\"name\":\"Peixoto na corrida \u00e0 C\u00e2mara Federal -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg\",\"datePublished\":\"2022-05-05T22:46:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg\",\"width\":768,\"height\":512,\"caption\":\"Sebasti\u00e3o Peixoto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/05\\\/05\\\/peixoto-na-corrida-a-camara-federal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peixoto na corrida \u00e0 C\u00e2mara Federal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peixoto na corrida \u00e0 C\u00e2mara Federal -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/","og_locale":"pt_BR","og_type":"article","og_title":"Peixoto na corrida \u00e0 C\u00e2mara Federal -","og_description":"Peixoto na corrida \u00e0 C\u00e2mara Federal Liberal quer fim do Fund\u00e3o Eleitoral Ele prop\u00f5e PEC para acabar com farra dos concurseiros Renato Dias O suplente de vereador Sebasti\u00e3o Peixoto anuncia, hoje, a sua pr\u00e9-candidatura \u00e0 C\u00e2mara dos Deputados. Legenda: Solidariedade. As elei\u00e7\u00f5es ocorrer\u00e3o dia 2; de outubro de 2022. Goi\u00e1s tem 17 cadeiras. Com 4","og_url":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2022-05-05T22:46:16+00:00","og_image":[{"width":360,"height":240,"url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/09\/Suplente-de-vereador-Sebastiao-Peixoto-e1646620052462.jpeg","type":"image\/jpeg"}],"author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"Peixoto na corrida \u00e0 C\u00e2mara Federal","datePublished":"2022-05-05T22:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/09\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg","articleSection":["Cinema"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/","url":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/","name":"Peixoto na corrida \u00e0 C\u00e2mara Federal -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/09\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg","datePublished":"2022-05-05T22:46:16+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#primaryimage","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/09\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/09\/Suplente-de-vereador-Sebastiao-Peixoto.jpeg","width":768,"height":512,"caption":"Sebasti\u00e3o Peixoto"},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2022\/05\/05\/peixoto-na-corrida-a-camara-federal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"Peixoto na corrida \u00e0 C\u00e2mara Federal"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/12213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=12213"}],"version-history":[{"count":1,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/12213\/revisions"}],"predecessor-version":[{"id":12214,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/12213\/revisions\/12214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media\/9162"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=12213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=12213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=12213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}