{"id":10819,"date":"2022-02-16T19:30:07","date_gmt":"2022-02-16T22:30:07","guid":{"rendered":"https:\/\/renatodias.online\/movimento\/?p=10819"},"modified":"2022-02-16T19:30:07","modified_gmt":"2022-02-16T22:30:07","slug":"o-que-diria-olavo-de-carvalho","status":"publish","type":"post","link":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/","title":{"rendered":"O que diria Olavo de Carvalho?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8379 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/08\/Especial-Principal.png\" alt=\"\" width=\"1531\" height=\"515\" \/><\/p>\n<h1 style=\"text-align: center;\"><strong><span style=\"color: #008000;\">Bolsonaro reverencia<\/span> <span style=\"color: #ff0000;\">comunistas<\/span><\/strong><\/h1>\n<h3 style=\"text-align: center;\"><span style=\"color: #808000;\"><strong>Vale tudo do autocrata desnorteia\u00a0a sua base eleitoral<\/strong><\/span><\/h3>\n<figure id=\"attachment_10821\" aria-describedby=\"caption-attachment-10821\" style=\"width: 1265px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10821 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Vladimir-Putin-e-Jair-Bolsonaro.jpg\" alt=\"\" width=\"1265\" height=\"760\" srcset=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Vladimir-Putin-e-Jair-Bolsonaro.jpg 1265w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Vladimir-Putin-e-Jair-Bolsonaro-300x180.jpg 300w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Vladimir-Putin-e-Jair-Bolsonaro-768x461.jpg 768w, https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Vladimir-Putin-e-Jair-Bolsonaro-750x451.jpg 750w\" sizes=\"auto, (max-width: 1265px) 100vw, 1265px\" \/><figcaption id=\"caption-attachment-10821\" class=\"wp-caption-text\"><strong>Vladimir Putin e Jair Bolsonaro, em Moscou _ O Globo<\/strong><\/figcaption><\/figure>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><\/p>\n<p><strong>Renato Dias<\/strong><\/p>\n<p>O anticomunismo, arma usada como tsunami de Fake News, em 2018, na elei\u00e7\u00e3o ao Pal\u00e1cio do Planalto, empoeirado, ao gosto da extinta Guerra Fria [1945-1991], virou p\u00f3, em Moscou. O suposto Messias, Jair Bolsonaro [PL] fez rever\u00eancia aos comunistas mortos. Um ato tradicional. Desde a revolu\u00e7\u00e3o de outubro de 1917.<\/p>\n<figure id=\"attachment_4014\" aria-describedby=\"caption-attachment-4014\" style=\"width: 373px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4014 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2020\/06\/Vladimir-Ilich-Ulianov-L\u00eanin-4.jpg\" alt=\"\" width=\"373\" height=\"500\" \/><figcaption id=\"caption-attachment-4014\" class=\"wp-caption-text\"><strong>Vladimir Ilich Ulianov \u2013 L\u00eanin<\/strong><\/figcaption><\/figure>\n<blockquote><p><span style=\"color: #008000;\"><strong>A Guerra Fria n\u00e3o continuava?<\/strong><\/span><\/p><\/blockquote>\n<p>Desnorteados. Assim, imp\u00e1vidos, est\u00e3o os adeptos das ideias da Terra Plana, que recusam o uso de m\u00e1scaras e desdenham da ado\u00e7\u00e3o da medida sanit\u00e1ria de confinamento. O ex &#8211; capit\u00e3o frisa que Vladimir Putin \u00e9 um amigo, desagrada a Joe Biden, est\u00e1 longe de Xi Jinping e distancia-se da Europa e das na\u00e7\u00f5es do Mercosul.<\/p>\n<figure id=\"attachment_8573\" aria-describedby=\"caption-attachment-8573\" style=\"width: 724px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8573 size-large\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/08\/Caricatura-de-Xi-Jinping-724x1024.jpg\" alt=\"\" width=\"724\" height=\"1024\" \/><figcaption id=\"caption-attachment-8573\" class=\"wp-caption-text\"><strong>Xi Jinping<\/strong><\/figcaption><\/figure>\n<blockquote><p><span style=\"color: #008000;\"><strong>Terraplanista \u00e9 enquadrado e isolado<\/strong><\/span><\/p><\/blockquote>\n<p>O homem que amea\u00e7ava invadir a Venezuela, parceira estrat\u00e9gica do Kremlin, n\u00e3o emitiu um ru\u00eddo que pudesse soar como sons ou palavras parecidos com o nome de Nicol\u00e1s Maduro. O herdeiro de Hugo Ch\u00e1vez no poder. Cuba, Nicar\u00e1gua, Bol\u00edvia, S\u00edria, Ir\u00e3? Um sil\u00eancio. Sepulcral. Do falastr\u00e3o. Com a palavra, Ernesto Ara\u00fajo.<\/p>\n<figure id=\"attachment_10134\" aria-describedby=\"caption-attachment-10134\" style=\"width: 754px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10134 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/12\/Nicolas-Maduro-ato-de-protesto.png\" alt=\"\" width=\"754\" height=\"644\" \/><figcaption id=\"caption-attachment-10134\" class=\"wp-caption-text\"><strong>Presidente eleito da Venezuela, Nicol\u00e1s Maduro<br \/><\/strong><\/figcaption><\/figure>\n<blockquote><p><span style=\"color: #008000;\"><strong>Ironias da Hist\u00f3ria<\/strong><\/span><\/p><\/blockquote>\n<p>N\u00facleos neonazistas no Brasil, insuflados pela intoler\u00e2ncia \u00e0 democracia emanados do denominado \u2018Gabinete do \u00d3dio\u2019, sob o controle de Carlos Bolsonaro, integrante da comitiva mesmo sem ocupar nenhum cargo na Uni\u00e3o,\u00a0devem estar \u00e0 beira de um ataque de nervos. O que diria Olavo de Carvalho, morto sem tomar vacinas?<\/p>\n<figure id=\"attachment_7680\" aria-describedby=\"caption-attachment-7680\" style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7680 size-full\" src=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2021\/07\/Olavo-de-Carvalho.jpg\" alt=\"\" width=\"1500\" height=\"1000\" \/><figcaption id=\"caption-attachment-7680\" class=\"wp-caption-text\"><strong>Olavo de Carvalho<\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bolsonaro reverencia comunistas Vale tudo do autocrata desnorteia\u00a0a sua base eleitoral \u00a0 Renato Dias O anticomunismo, arma usada como tsunami de Fake News, em 2018, na elei\u00e7\u00e3o ao Pal\u00e1cio do Planalto, empoeirado, ao gosto da extinta Guerra Fria [1945-1991], virou p\u00f3, em Moscou. O suposto Messias, Jair Bolsonaro [PL] fez rever\u00eancia aos comunistas mortos. Um<\/p>\n","protected":false},"author":2,"featured_media":10820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-10819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que diria Olavo de Carvalho? -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que diria Olavo de Carvalho? -\" \/>\n<meta property=\"og:description\" content=\"Bolsonaro reverencia comunistas Vale tudo do autocrata desnorteia\u00a0a sua base eleitoral \u00a0 Renato Dias O anticomunismo, arma usada como tsunami de Fake News, em 2018, na elei\u00e7\u00e3o ao Pal\u00e1cio do Planalto, empoeirado, ao gosto da extinta Guerra Fria [1945-1991], virou p\u00f3, em Moscou. O suposto Messias, Jair Bolsonaro [PL] fez rever\u00eancia aos comunistas mortos. Um\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/renato.dias.37\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-16T22:30:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Jair-Bolsonaro-em-Moscou.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Dias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:site\" content=\"@RenatoDiasBat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renato Dias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/\"},\"author\":{\"name\":\"Renato Dias\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"headline\":\"O que diria Olavo de Carvalho?\",\"datePublished\":\"2022-02-16T22:30:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Jair-Bolsonaro-em-Moscou.jpg\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/\",\"name\":\"O que diria Olavo de Carvalho? -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Jair-Bolsonaro-em-Moscou.jpg\",\"datePublished\":\"2022-02-16T22:30:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Jair-Bolsonaro-em-Moscou.jpg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Jair-Bolsonaro-em-Moscou.jpg\",\"width\":1000,\"height\":668,\"caption\":\"Jair Bolsonaro em Moscou\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/2022\\\/02\\\/16\\\/o-que-diria-olavo-de-carvalho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que diria Olavo de Carvalho?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#website\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/#\\\/schema\\\/person\\\/bbab28833b1725a20f4083f49f1fb2a9\",\"name\":\"Renato Dias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"contentUrl\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\",\"width\":1280,\"height\":219,\"caption\":\"Renato Dias\"},\"logo\":{\"@id\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-cropped-cropped-logofinal.jpeg\"},\"description\":\"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/renato.dias.37\",\"#breve\",\"https:\\\/\\\/renatodias.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/renatodias.online\\\/movimento\\\/author\\\/renatodias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que diria Olavo de Carvalho? -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/","og_locale":"pt_BR","og_type":"article","og_title":"O que diria Olavo de Carvalho? -","og_description":"Bolsonaro reverencia comunistas Vale tudo do autocrata desnorteia\u00a0a sua base eleitoral \u00a0 Renato Dias O anticomunismo, arma usada como tsunami de Fake News, em 2018, na elei\u00e7\u00e3o ao Pal\u00e1cio do Planalto, empoeirado, ao gosto da extinta Guerra Fria [1945-1991], virou p\u00f3, em Moscou. O suposto Messias, Jair Bolsonaro [PL] fez rever\u00eancia aos comunistas mortos. Um","og_url":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/","article_publisher":"https:\/\/www.facebook.com\/renato.dias.37","article_author":"https:\/\/www.facebook.com\/renato.dias.37","article_published_time":"2022-02-16T22:30:07+00:00","og_image":[{"width":1000,"height":668,"url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Jair-Bolsonaro-em-Moscou.jpg","type":"image\/jpeg"}],"author":"Renato Dias","twitter_card":"summary_large_image","twitter_creator":"@RenatoDiasBat","twitter_site":"@RenatoDiasBat","twitter_misc":{"Escrito por":"Renato Dias","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#article","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/"},"author":{"name":"Renato Dias","@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"headline":"O que diria Olavo de Carvalho?","datePublished":"2022-02-16T22:30:07+00:00","mainEntityOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Jair-Bolsonaro-em-Moscou.jpg","articleSection":["Internacional"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/","url":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/","name":"O que diria Olavo de Carvalho? -","isPartOf":{"@id":"https:\/\/renatodias.online\/movimento\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#primaryimage"},"image":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#primaryimage"},"thumbnailUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Jair-Bolsonaro-em-Moscou.jpg","datePublished":"2022-02-16T22:30:07+00:00","breadcrumb":{"@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#primaryimage","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Jair-Bolsonaro-em-Moscou.jpg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2022\/02\/Jair-Bolsonaro-em-Moscou.jpg","width":1000,"height":668,"caption":"Jair Bolsonaro em Moscou"},{"@type":"BreadcrumbList","@id":"https:\/\/renatodias.online\/movimento\/2022\/02\/16\/o-que-diria-olavo-de-carvalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/renatodias.online\/movimento\/"},{"@type":"ListItem","position":2,"name":"O que diria Olavo de Carvalho?"}]},{"@type":"WebSite","@id":"https:\/\/renatodias.online\/movimento\/#website","url":"https:\/\/renatodias.online\/movimento\/","name":"","description":"","publisher":{"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renatodias.online\/movimento\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/renatodias.online\/movimento\/#\/schema\/person\/bbab28833b1725a20f4083f49f1fb2a9","name":"Renato Dias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","url":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","contentUrl":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg","width":1280,"height":219,"caption":"Renato Dias"},"logo":{"@id":"https:\/\/renatodias.online\/movimento\/wp-content\/uploads\/2023\/03\/cropped-cropped-cropped-logofinal.jpeg"},"description":"Renato Dias, 58 anos, \u00e9 graduado em Jornalismo, formado em Ci\u00eancias Sociais, com p\u00f3s-gradua\u00e7\u00e3o em Pol\u00edticas P\u00fablicas, mestre em Direito e Rela\u00e7\u00f5es Internacionais, ex-aluno extraordin\u00e1rio do Doutorado em Psicologia Social, ex-estudante do Curso de Psican\u00e1lise do Centro de Estudos Psicanal\u00edticos do Estado de Goi\u00e1s, ministrado pelo m\u00e9dico psiquiatra e psicanalista Daniel Em\u00eddio de Souza. \u00c9 autor de 30 livros-reportagem, oito document\u00e1rios, ganhou 30 pr\u00eamios e \u00e9 torcedor apaixonado do maior do Centro-Oeste, o Vila Nova Futebol Clube. Casado com Meirilane Dias, \u00e9 pai de Juliana Dias, jornalista; Daniel Dias, economista; e Maria Rosa Dias, estudante antifascista, socialista e trotskista.\u00a0Com tr\u00eas pets: Porquinho [Bull Dog Franc\u00eas], Dalila [Basset Hound] e Geleia [Basset Hound]. Al\u00e9m do eterno gato Tutuquinho, que virou estrela.","sameAs":["https:\/\/www.facebook.com\/renato.dias.37","#breve","https:\/\/renatodias.tumblr.com\/"],"url":"https:\/\/renatodias.online\/movimento\/author\/renatodias\/"}]}},"_links":{"self":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/10819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/comments?post=10819"}],"version-history":[{"count":1,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/10819\/revisions"}],"predecessor-version":[{"id":10822,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/posts\/10819\/revisions\/10822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media\/10820"}],"wp:attachment":[{"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/media?parent=10819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/categories?post=10819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatodias.online\/movimento\/wp-json\/wp\/v2\/tags?post=10819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}